{"id":136,"count":27,"description":"Una linea completa di battiscopa in MDF, disponibili in un'ampia scelta di colorazioni per poterli facilmente abbinare al colore del vostro pavimento in laminato.\r\nUna scelta pratica e conveniente per un prodotto di alta qualit\u00e0, realizzato con un rivestimento di resistente carta mela mminica decorativa, su un robusto supporto in MDF.\r\nDiverse colorazioni per una carta mela mminica lavabile e resistente nel tempo alle abrasioni, sollecitazioni. Garantiamo la sua brillantezza e il suo colore nel tempo.\r\nSupporto in MDF (Medium Density Fibreboard) a basso contenuto di formaldeide in osservanza delle norme E1, realizzato utilizzando legno proveniente da foreste certificate FSC.\r\nColla eco sostenibile termica per un'aderenza garantita.\r\nPosa con colla o chiodini semplicissima anche per un lavoro \"fai date\" per i meno esperti.\r\nDisponibili in due altezze diverse da 58 e 80 mm con una lunghezza standard di 240 cm.\r\n\r\nNon trovi il colore o sei in dubbio? Non preoccuparti, <a href=\"https:\/\/prodotto\/battiscopa-in-tinta\/\">CLICCA QUI <\/a>e penseremo noi ad inviarti quello corretto.","link":"https:\/\/pavimentiamo.it\/en\/product-category\/accessori\/battiscopa-accessori\/battiscopa-in-mdf\/","name":"BATTISCOPA IN MDF","slug":"battiscopa-in-mdf","taxonomy":"product_cat","parent":134,"meta":[],"_links":{"self":[{"href":"https:\/\/pavimentiamo.it\/en\/wp-json\/wp\/v2\/product_cat\/136","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pavimentiamo.it\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/pavimentiamo.it\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/pavimentiamo.it\/en\/wp-json\/wp\/v2\/product_cat\/134"}],"wp:post_type":[{"href":"https:\/\/pavimentiamo.it\/en\/wp-json\/wp\/v2\/product?product_cat=136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}