{"id":3009,"date":"2019-04-17T15:30:13","date_gmt":"2019-04-17T13:30:13","guid":{"rendered":"https:\/\/?post_type=product&#038;p=3009"},"modified":"2024-04-03T22:55:08","modified_gmt":"2024-04-03T20:55:08","slug":"profilo-per-laminati-pari-livello-legno-93","status":"publish","type":"product","link":"https:\/\/pavimentiamo.it\/en\/product\/profilo-per-laminati-pari-livello-legno-93\/","title":{"rendered":"PROFILO PER LAMINATI PARI LIVELLO  LEGNO 93"},"content":{"rendered":"<p>Profilo Z\/1 a T in alluminio rivestito in tinta con una resistente pellicola mellaminica decorata, da utilizzare come giunto di dilatazione e raccordo di pari livello per pavimenti complanari.<br \/>\nSpecific for laminate floors.<\/p>","protected":false},"excerpt":{"rendered":"<p>Profilo Z\/1 a T in alluminio rivestito in tinta con una resistente pellicola mellaminica decorata, da utilizzare come giunto di dilatazione e raccordo di pari livello per pavimenti complanari. Specifico per pavimenti in laminato.<\/p>","protected":false},"featured_media":0,"template":"","meta":[],"product_cat":[91,152,138,146],"product_tag":[],"class_list":{"0":"post-3009","1":"product","2":"type-product","3":"status-publish","5":"product_cat-accessori","6":"product_cat-giunto-dilatazione-pari-livello","7":"product_cat-profili-accessori","8":"product_cat-profili-laminati-profili-accessori","9":"product_shipping_class-accessori","11":"first","12":"outofstock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-variable"},"_links":{"self":[{"href":"https:\/\/pavimentiamo.it\/en\/wp-json\/wp\/v2\/product\/3009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pavimentiamo.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/pavimentiamo.it\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/pavimentiamo.it\/en\/wp-json\/wp\/v2\/media?parent=3009"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/pavimentiamo.it\/en\/wp-json\/wp\/v2\/product_cat?post=3009"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/pavimentiamo.it\/en\/wp-json\/wp\/v2\/product_tag?post=3009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}